{"id":14,"date":"2022-10-18T20:33:17","date_gmt":"2022-10-18T20:33:17","guid":{"rendered":"https:\/\/observacom.org\/compartetucaso\/?page_id=14"},"modified":"2023-03-10T00:22:05","modified_gmt":"2023-03-10T00:22:05","slug":"home","status":"publish","type":"page","link":"https:\/\/observacom.org\/compartetucaso\/","title":{"rendered":""},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"14\" class=\"elementor elementor-14\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc4aa0b elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc4aa0b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-20a831a\" data-id=\"20a831a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-791e0cd elementor-absolute elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"791e0cd\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"63\" src=\"https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/Observacom-logo-blanco-300x63.png\" class=\"attachment-medium size-medium wp-image-160\" alt=\"\" srcset=\"https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/Observacom-logo-blanco-300x63.png 300w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/Observacom-logo-blanco-1024x214.png 1024w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/Observacom-logo-blanco-768x160.png 768w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/Observacom-logo-blanco.png 1092w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-20dedb9\" data-id=\"20dedb9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-297e351 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"297e351\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2280\" height=\"468\" src=\"https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/Comparte-Tu-Caso.png\" class=\"attachment-full size-full wp-image-242\" alt=\"\" srcset=\"https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/Comparte-Tu-Caso.png 2280w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/Comparte-Tu-Caso-300x62.png 300w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/Comparte-Tu-Caso-1024x210.png 1024w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/Comparte-Tu-Caso-768x158.png 768w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/Comparte-Tu-Caso-1536x315.png 1536w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/Comparte-Tu-Caso-2048x420.png 2048w\" sizes=\"auto, (max-width: 2280px) 100vw, 2280px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b911fa0\" data-id=\"b911fa0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e1e542b elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e1e542b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-be70c8d\" data-id=\"be70c8d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-8ed1758\" data-id=\"8ed1758\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77a3eca elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"77a3eca\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Las remociones de contenidos que usan las grandes plataformas por supuestamente incumplir sus t\u00e9rminos de servicio o normas comunitarias es una grave y unilateral medida que puede afectar el derecho a la libertad de expresi\u00f3n de quien publica, pero tambi\u00e9n del que busca y tiene derecho a recibir esa publicaci\u00f3n.<\/p><p>La suspensi\u00f3n o bloqueo de una cuenta en una red social es una medida a\u00fan m\u00e1s dr\u00e1stica: excluye totalmente a su titular de los nuevos espacios p\u00fablicos en Internet.<\/p><p>Conocer los casos en que esto sucede nos permite conocer c\u00f3mo funciona la moderaci\u00f3n de contenidos de las grandes plataformas y poder tener m\u00e1s elementos para proteger la libertad de expresi\u00f3n en l\u00ednea, con la finalidad de empoderar a los usuarios de redes sociales para que conozcan sus derechos y puedan reaccionar ante decisiones que consideran injustas.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-90cd376\" data-id=\"90cd376\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a0661a6 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a0661a6\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c73d753\" data-id=\"c73d753\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f3049b elementor-widget elementor-widget-image\" data-id=\"6f3049b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"139\" src=\"https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/banner-compartetucaso-1024x139.png\" class=\"attachment-large size-large wp-image-169\" alt=\"\" srcset=\"https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/banner-compartetucaso-1024x139.png 1024w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/banner-compartetucaso-300x41.png 300w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/banner-compartetucaso-768x105.png 768w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/banner-compartetucaso-1536x209.png 1536w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/banner-compartetucaso-2048x279.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-366d346 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"366d346\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-10b9349\" data-id=\"10b9349\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37974ab elementor-widget elementor-widget-spacer\" data-id=\"37974ab\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7515580 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7515580\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5e9756a\" data-id=\"5e9756a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a33be59\" data-id=\"a33be59\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2766796 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"2766796\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h3 class=\"elementor-heading-title elementor-size-default\">Completa este formulario si te\npas\u00f3 algo as\u00ed o conoces alguien que le haya sucedido.<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-64ee02c\" data-id=\"64ee02c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-08573c9 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"08573c9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c6db1fc\" data-id=\"c6db1fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fd82b2 elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"3fd82b2\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e9a1ad elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e9a1ad\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f9fdeb0\" data-id=\"f9fdeb0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-058efb0 elementor-widget elementor-widget-spacer\" data-id=\"058efb0\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05e7533 elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-wpforms\" data-id=\"05e7533\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-43\"><form id=\"wpforms-form-43\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"43\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/compartetucaso\/index.php\/wp-json\/wp\/v2\/pages\/14?wpforms_form_id=43\" data-token=\"e1194c0d162e4e2b9f647841661e736b\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-43-field_8-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_8\">\u00bfCu\u00e1les de estos tipos de restricci\u00f3n has sufrido? <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-43-field_8\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][8]\" required=\"required\"><option value=\"-\" >-<\/option><option value=\"Remoci\u00f3n de un contenido publicado\" >Remoci\u00f3n de un contenido publicado<\/option><option value=\"Imposibilidad de publicar un contenido\" >Imposibilidad de publicar un contenido<\/option><option value=\"Desindexaci\u00f3n de contenido\" >Desindexaci\u00f3n de contenido<\/option><option value=\"Suspensi\u00f3n temporal de tu cuenta\/perfil\" >Suspensi\u00f3n temporal de tu cuenta\/perfil<\/option><option value=\"Suspensi\u00f3n o bloqueo permanente de tu cuenta\/perfil\" >Suspensi\u00f3n o bloqueo permanente de tu cuenta\/perfil<\/option><option value=\"Otra\" >Otra<\/option><\/select><\/div><div id=\"wpforms-43-field_9-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_9\">\u00bfEn cu\u00e1l plataforma sucedi\u00f3? <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-43-field_9\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][9]\" required=\"required\"><option value=\"-\" >-<\/option><option value=\"Facebook\" >Facebook<\/option><option value=\"Twitter\" >Twitter<\/option><option value=\"YouTube\" >YouTube<\/option><option value=\"Instagram\" >Instagram<\/option><option value=\"Google\" >Google<\/option><option value=\"TikTok\" >TikTok<\/option><option value=\"Otra\" >Otra<\/option><\/select><\/div><div id=\"wpforms-43-field_5-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_5\">\u00bfCu\u00e1ndo sucedi\u00f3? <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-43-field_5\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][5][date]\" required><a title=\"Borrar fecha\" data-clear class=\"wpforms-datepicker-clear\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-43-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_6\">\u00bfCu\u00e1l es la URL de tu cuenta? <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-43-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" required><\/div><div id=\"wpforms-43-field_10-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_10\">\u00bfCu\u00e1l es la raz\u00f3n que te dio la plataforma? <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-43-field_10\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][10]\" required=\"required\"><option value=\"-\" >-<\/option><option value=\"Incumple t\u00e9rminos de servicio o normas comunitarias\" >Incumple t\u00e9rminos de servicio o normas comunitarias<\/option><option value=\"Reportado o denunciado por terceros\" >Reportado o denunciado por terceros<\/option><option value=\"Actividad inusual o maliciosa\" >Actividad inusual o maliciosa<\/option><option value=\"Spam\" >Spam<\/option><option value=\"Ninguna\" >Ninguna<\/option><option value=\"Otra\" >Otra<\/option><\/select><\/div><div id=\"wpforms-43-field_11-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_11\">\u00bfQu\u00e9 tipo de contenido motiv\u00f3 la restricci\u00f3n (textos, im\u00e1genes, videos)? <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-43-field_11\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][11]\" required=\"required\"><option value=\"-\" >-<\/option><option value=\"Contenido informativo (propio o de otras fuentes como entrevistas, art\u00edculos, etc.)\" >Contenido informativo (propio o de otras fuentes como entrevistas, art\u00edculos, etc.)<\/option><option value=\"Comentario u opini\u00f3n sobre un determinado tema o hecho\" >Comentario u opini\u00f3n sobre un determinado tema o hecho<\/option><option value=\"Contenido personal o familiar\" >Contenido personal o familiar<\/option><option value=\"Contenido art\u00edstico, cultural o similar\" >Contenido art\u00edstico, cultural o similar<\/option><option value=\"Contenido sat\u00edrico, humor\u00edstico, par\u00f3dico o similar\" >Contenido sat\u00edrico, humor\u00edstico, par\u00f3dico o similar<\/option><option value=\"Otro\" >Otro<\/option><\/select><\/div><div id=\"wpforms-43-field_12-container\" class=\"wpforms-field wpforms-field-radio\" data-field-id=\"12\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_12\">\u00bfApelaste la decisi\u00f3n de la plataforma? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-43-field_12\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-43-field_12_1\" name=\"wpforms[fields][12]\" value=\"Si\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-43-field_12_1\">Si<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-43-field_12_2\" name=\"wpforms[fields][12]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-43-field_12_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-43-field_13-container\" class=\"wpforms-field wpforms-field-radio\" data-field-id=\"13\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_13\">\u00bfTu cuenta o contenido fue restablecido? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-43-field_13\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-43-field_13_1\" name=\"wpforms[fields][13]\" value=\"Si\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-43-field_13_1\">Si<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-43-field_13_2\" name=\"wpforms[fields][13]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-43-field_13_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-43-field_14-container\" class=\"wpforms-field wpforms-field-textarea wpforms-one\" data-field-id=\"14\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_14\">\u00bfPuedes decirnos, brevemente, por qu\u00e9 crees que es una decisi\u00f3n injusta?<\/label><textarea id=\"wpforms-43-field_14\" class=\"wpforms-field-medium\" name=\"wpforms[fields][14]\" ><\/textarea><\/div><div id=\"wpforms-43-field_15-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-id=\"15\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_15\">Adjuntar captura del contenido restringido<\/label><div class=\"wpforms-uploader\"\n\tdata-field-id=\"15\"\n\tdata-form-id=\"43\"\n\tdata-input-name=\"wpforms_43_15\"\n\tdata-extensions=\"jpg,jpeg,jpe,gif,png,bmp,tiff,tif,webp,avif,ico,heic,heif,heics,heifs,asf,asx,wmv,wmx,wm,avi,divx,mov,qt,mpeg,mpg,mpe,mp4,m4v,ogv,webm,mkv,3gp,3gpp,3g2,3gp2,txt,asc,c,cc,h,srt,csv,tsv,ics,rtx,css,vtt,mp3,m4a,m4b,aac,ra,ram,wav,ogg,oga,flac,mid,midi,wma,wax,mka,rtf,pdf,class,tar,zip,gz,gzip,rar,7z,psd,xcf,doc,pot,pps,ppt,wri,xla,xls,xlt,xlw,mpp,docx,docm,dotx,dotm,xlsx,xlsm,xlsb,xltx,xltm,xlam,pptx,pptm,ppsx,ppsm,potx,potm,ppam,sldx,sldm,onetoc,onetoc2,onepkg,oxps,xps,odt,odp,ods,odg,odc,odb,odf,wp,wpd,key,numbers,pages\"\n\tdata-max-size=\"268435456\"\n\tdata-max-file-number=\"1\"\n\tdata-post-max-size=\"268435456\"\n    data-max-parallel-uploads=\"4\"\n    data-parallel-uploads=\"true\"\n\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg viewBox=\"0 0 1024 1024\" focusable=\"false\" class=\"\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"#B1B1B1\" aria-hidden=\"true\"><path d=\"M885.2 446.3l-.2-.8-112.2-285.1c-5-16.1-19.9-27.2-36.8-27.2H281.2c-17 0-32.1 11.3-36.9 27.6L139.4 443l-.3.7-.2.8c-1.3 4.9-1.7 9.9-1 14.8-.1 1.6-.2 3.2-.2 4.8V830a60.9 60.9 0 0 0 60.8 60.8h627.2c33.5 0 60.8-27.3 60.9-60.8V464.1c0-1.3 0-2.6-.1-3.7.4-4.9 0-9.6-1.3-14.1zm-295.8-43l-.3 15.7c-.8 44.9-31.8 75.1-77.1 75.1-22.1 0-41.1-7.1-54.8-20.6S436 441.2 435.6 419l-.3-15.7H229.5L309 210h399.2l81.7 193.3H589.4zm-375 76.8h157.3c24.3 57.1 76 90.8 140.4 90.8 33.7 0 65-9.4 90.3-27.2 22.2-15.6 39.5-37.4 50.7-63.6h156.5V814H214.4V480.1z\"><\/path><\/svg>\n\t\t<span class=\"modern-title\">\n\t\t\tHaz clic o arrastra un archivo a este \u00e1rea para subirlo.\t\t<\/span>\n\n\t\t\t<\/div>\n<\/div>\n<input type=\"text\" class=\"dropzone-input\"\n\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\tid=\"wpforms-43-field_15\"\n\tname=\"wpforms_43_15\" >\n<div class=\"wpforms-field-description\">Estas informaciones son \u00fatiles para entender el caso. No es obligatorio que la envies.<\/div><\/div><div id=\"wpforms-43-field_18-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-id=\"18\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_18\">Adjuntar captura de la notificaci\u00f3n de la plataforma<\/label><div class=\"wpforms-uploader\"\n\tdata-field-id=\"18\"\n\tdata-form-id=\"43\"\n\tdata-input-name=\"wpforms_43_18\"\n\tdata-extensions=\"jpg,jpeg,jpe,gif,png,bmp,tiff,tif,webp,avif,ico,heic,heif,heics,heifs,asf,asx,wmv,wmx,wm,avi,divx,mov,qt,mpeg,mpg,mpe,mp4,m4v,ogv,webm,mkv,3gp,3gpp,3g2,3gp2,txt,asc,c,cc,h,srt,csv,tsv,ics,rtx,css,vtt,mp3,m4a,m4b,aac,ra,ram,wav,ogg,oga,flac,mid,midi,wma,wax,mka,rtf,pdf,class,tar,zip,gz,gzip,rar,7z,psd,xcf,doc,pot,pps,ppt,wri,xla,xls,xlt,xlw,mpp,docx,docm,dotx,dotm,xlsx,xlsm,xlsb,xltx,xltm,xlam,pptx,pptm,ppsx,ppsm,potx,potm,ppam,sldx,sldm,onetoc,onetoc2,onepkg,oxps,xps,odt,odp,ods,odg,odc,odb,odf,wp,wpd,key,numbers,pages\"\n\tdata-max-size=\"268435456\"\n\tdata-max-file-number=\"1\"\n\tdata-post-max-size=\"268435456\"\n    data-max-parallel-uploads=\"4\"\n    data-parallel-uploads=\"true\"\n\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg viewBox=\"0 0 1024 1024\" focusable=\"false\" class=\"\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"#B1B1B1\" aria-hidden=\"true\"><path d=\"M885.2 446.3l-.2-.8-112.2-285.1c-5-16.1-19.9-27.2-36.8-27.2H281.2c-17 0-32.1 11.3-36.9 27.6L139.4 443l-.3.7-.2.8c-1.3 4.9-1.7 9.9-1 14.8-.1 1.6-.2 3.2-.2 4.8V830a60.9 60.9 0 0 0 60.8 60.8h627.2c33.5 0 60.8-27.3 60.9-60.8V464.1c0-1.3 0-2.6-.1-3.7.4-4.9 0-9.6-1.3-14.1zm-295.8-43l-.3 15.7c-.8 44.9-31.8 75.1-77.1 75.1-22.1 0-41.1-7.1-54.8-20.6S436 441.2 435.6 419l-.3-15.7H229.5L309 210h399.2l81.7 193.3H589.4zm-375 76.8h157.3c24.3 57.1 76 90.8 140.4 90.8 33.7 0 65-9.4 90.3-27.2 22.2-15.6 39.5-37.4 50.7-63.6h156.5V814H214.4V480.1z\"><\/path><\/svg>\n\t\t<span class=\"modern-title\">\n\t\t\tHaz clic o arrastra un archivo a este \u00e1rea para subirlo.\t\t<\/span>\n\n\t\t\t<\/div>\n<\/div>\n<input type=\"text\" class=\"dropzone-input\"\n\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\tid=\"wpforms-43-field_18\"\n\tname=\"wpforms_43_18\" >\n<div class=\"wpforms-field-description\">Estas informaciones son \u00fatiles para entender el caso. No es obligatorio que la envies.<\/div><\/div><div id=\"wpforms-43-field_16-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"16\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_16\">Tu mail <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-43-field_16\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][16]\" required><\/div><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"43\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" class=\"wpforms-submit \" id=\"wpforms-submit-43\" value=\"wpforms-submit\" aria-live=\"assertive\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\">Enviar<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/observacom.org\/compartetucaso\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86373c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86373c1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b87b45a\" data-id=\"b87b45a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7281298 elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"7281298\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58981a7 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58981a7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a2d5b9\" data-id=\"2a2d5b9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a789a0b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a789a0b\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#2c2c2c;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-03efb4c elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"03efb4c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-96605fa\" data-id=\"96605fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ade4de8 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"ade4de8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"MsoNormal\" style=\"margin-bottom: 6.0pt;\"><b>RESERVA DE TU INFORMACI\u00d3N PERSONAL<br \/><\/b>En nuestro formulario no te solicitamos como dato obligatorio tu nombre y nos comprometemos a conservar confidencialidad de esta informaci\u00f3n que compartes, que s\u00f3lo haremos p\u00fablica con tu aprobaci\u00f3n previa y expresa.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-228cc7d elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"228cc7d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a3ff973\" data-id=\"a3ff973\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed73b8d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ed73b8d\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9d3d9e2 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9d3d9e2\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8f83824\" data-id=\"8f83824\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a7b9af elementor-widget elementor-widget-image\" data-id=\"2a7b9af\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"210\" src=\"https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/Comparte-Tu-Caso-1024x210.png\" class=\"attachment-large size-large wp-image-242\" alt=\"\" srcset=\"https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/Comparte-Tu-Caso-1024x210.png 1024w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/Comparte-Tu-Caso-300x62.png 300w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/Comparte-Tu-Caso-768x158.png 768w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/Comparte-Tu-Caso-1536x315.png 1536w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/Comparte-Tu-Caso-2048x420.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ba055c elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ba055c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-52062f3\" data-id=\"52062f3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-672d298\" data-id=\"672d298\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5cf035c elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"5cf035c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/elementor\/thumbs\/Observacom-logo-blanco-px2vj43i0udkibgt5mturco0rw2c5hr2ujhed9m2eu.png\" title=\"Observacom logo blanco\" alt=\"Observacom logo blanco\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-2975071\" data-id=\"2975071\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b36ccaf elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b36ccaf\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50474b8\" data-id=\"50474b8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ca13ef elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"9ca13ef\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Las remociones de contenidos que usan las grandes plataformas por supuestamente incumplir sus t\u00e9rminos de servicio o normas comunitarias es una grave y unilateral medida que puede afectar el derecho a la libertad de expresi\u00f3n de quien publica, pero tambi\u00e9n del que busca y tiene derecho a recibir esa publicaci\u00f3n.<\/p><p>La suspensi\u00f3n o bloqueo de una cuenta en una red social es una medida a\u00fan m\u00e1s dr\u00e1stica: excluye totalmente a su titular de los nuevos espacios p\u00fablicos en Internet.<\/p><p>Conocer los casos en que esto sucede nos permite conocer c\u00f3mo funciona la moderaci\u00f3n de contenidos de las grandes plataformas y poder tener m\u00e1s elementos para proteger la libertad de expresi\u00f3n en l\u00ednea, con la finalidad de empoderar a los usuarios de redes sociales para que conozcan sus derechos y puedan reaccionar ante decisiones que consideran injustas.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a7135d7 elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-section-height-default elementor-section-height-default\" data-id=\"a7135d7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d901efc\" data-id=\"d901efc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8456a94 elementor-widget elementor-widget-image\" data-id=\"8456a94\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"10341\" height=\"1408\" src=\"https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/banner-compartetucaso.png\" class=\"attachment-full size-full wp-image-169\" alt=\"\" srcset=\"https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/banner-compartetucaso.png 10341w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/banner-compartetucaso-300x41.png 300w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/banner-compartetucaso-1024x139.png 1024w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/banner-compartetucaso-768x105.png 768w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/banner-compartetucaso-1536x209.png 1536w, https:\/\/observacom.org\/compartetucaso\/wp-content\/uploads\/2022\/11\/banner-compartetucaso-2048x279.png 2048w\" sizes=\"auto, (max-width: 10341px) 100vw, 10341px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8f2dfe elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8f2dfe\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9eb83a7\" data-id=\"9eb83a7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ee906d elementor-widget elementor-widget-spacer\" data-id=\"3ee906d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f28076 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f28076\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-b96eb86\" data-id=\"b96eb86\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a60e0bd\" data-id=\"a60e0bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-00dbbe6 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"00dbbe6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Completa este formulario si te pas\u00f3 algo as\u00ed\no conoces alguien que le haya sucedido.<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-10e8431\" data-id=\"10e8431\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e2f21e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e2f21e0\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-05d3762\" data-id=\"05d3762\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3e71fc elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-spacer\" data-id=\"d3e71fc\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6472842 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6472842\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-02caab4\" data-id=\"02caab4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-356968a elementor-widget__width-auto elementor-absolute elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-wpforms\" data-id=\"356968a\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-43\"><form id=\"wpforms-form-43\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"43\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/compartetucaso\/index.php\/wp-json\/wp\/v2\/pages\/14?wpforms_form_id=43\" data-token=\"e1194c0d162e4e2b9f647841661e736b\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-43-field_8-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_8\">\u00bfCu\u00e1les de estos tipos de restricci\u00f3n has sufrido? <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-43-field_8\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][8]\" required=\"required\"><option value=\"-\" >-<\/option><option value=\"Remoci\u00f3n de un contenido publicado\" >Remoci\u00f3n de un contenido publicado<\/option><option value=\"Imposibilidad de publicar un contenido\" >Imposibilidad de publicar un contenido<\/option><option value=\"Desindexaci\u00f3n de contenido\" >Desindexaci\u00f3n de contenido<\/option><option value=\"Suspensi\u00f3n temporal de tu cuenta\/perfil\" >Suspensi\u00f3n temporal de tu cuenta\/perfil<\/option><option value=\"Suspensi\u00f3n o bloqueo permanente de tu cuenta\/perfil\" >Suspensi\u00f3n o bloqueo permanente de tu cuenta\/perfil<\/option><option value=\"Otra\" >Otra<\/option><\/select><\/div><div id=\"wpforms-43-field_9-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_9\">\u00bfEn cu\u00e1l plataforma sucedi\u00f3? <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-43-field_9\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][9]\" required=\"required\"><option value=\"-\" >-<\/option><option value=\"Facebook\" >Facebook<\/option><option value=\"Twitter\" >Twitter<\/option><option value=\"YouTube\" >YouTube<\/option><option value=\"Instagram\" >Instagram<\/option><option value=\"Google\" >Google<\/option><option value=\"TikTok\" >TikTok<\/option><option value=\"Otra\" >Otra<\/option><\/select><\/div><div id=\"wpforms-43-field_5-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_5\">\u00bfCu\u00e1ndo sucedi\u00f3? <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-43-field_5\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][5][date]\" required><a title=\"Borrar fecha\" data-clear class=\"wpforms-datepicker-clear\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-43-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_6\">\u00bfCu\u00e1l es la URL de tu cuenta? <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-43-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" required><\/div><div id=\"wpforms-43-field_10-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_10\">\u00bfCu\u00e1l es la raz\u00f3n que te dio la plataforma? <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-43-field_10\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][10]\" required=\"required\"><option value=\"-\" >-<\/option><option value=\"Incumple t\u00e9rminos de servicio o normas comunitarias\" >Incumple t\u00e9rminos de servicio o normas comunitarias<\/option><option value=\"Reportado o denunciado por terceros\" >Reportado o denunciado por terceros<\/option><option value=\"Actividad inusual o maliciosa\" >Actividad inusual o maliciosa<\/option><option value=\"Spam\" >Spam<\/option><option value=\"Ninguna\" >Ninguna<\/option><option value=\"Otra\" >Otra<\/option><\/select><\/div><div id=\"wpforms-43-field_11-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_11\">\u00bfQu\u00e9 tipo de contenido motiv\u00f3 la restricci\u00f3n (textos, im\u00e1genes, videos)? <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-43-field_11\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][11]\" required=\"required\"><option value=\"-\" >-<\/option><option value=\"Contenido informativo (propio o de otras fuentes como entrevistas, art\u00edculos, etc.)\" >Contenido informativo (propio o de otras fuentes como entrevistas, art\u00edculos, etc.)<\/option><option value=\"Comentario u opini\u00f3n sobre un determinado tema o hecho\" >Comentario u opini\u00f3n sobre un determinado tema o hecho<\/option><option value=\"Contenido personal o familiar\" >Contenido personal o familiar<\/option><option value=\"Contenido art\u00edstico, cultural o similar\" >Contenido art\u00edstico, cultural o similar<\/option><option value=\"Contenido sat\u00edrico, humor\u00edstico, par\u00f3dico o similar\" >Contenido sat\u00edrico, humor\u00edstico, par\u00f3dico o similar<\/option><option value=\"Otro\" >Otro<\/option><\/select><\/div><div id=\"wpforms-43-field_12-container\" class=\"wpforms-field wpforms-field-radio\" data-field-id=\"12\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_12\">\u00bfApelaste la decisi\u00f3n de la plataforma? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-43-field_12\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-43-field_12_1\" name=\"wpforms[fields][12]\" value=\"Si\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-43-field_12_1\">Si<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-43-field_12_2\" name=\"wpforms[fields][12]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-43-field_12_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-43-field_13-container\" class=\"wpforms-field wpforms-field-radio\" data-field-id=\"13\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_13\">\u00bfTu cuenta o contenido fue restablecido? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-43-field_13\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-43-field_13_1\" name=\"wpforms[fields][13]\" value=\"Si\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-43-field_13_1\">Si<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-43-field_13_2\" name=\"wpforms[fields][13]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-43-field_13_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-43-field_14-container\" class=\"wpforms-field wpforms-field-textarea wpforms-one\" data-field-id=\"14\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_14\">\u00bfPuedes decirnos, brevemente, por qu\u00e9 crees que es una decisi\u00f3n injusta?<\/label><textarea id=\"wpforms-43-field_14\" class=\"wpforms-field-medium\" name=\"wpforms[fields][14]\" ><\/textarea><\/div><div id=\"wpforms-43-field_15-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-id=\"15\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_15\">Adjuntar captura del contenido restringido<\/label><div class=\"wpforms-uploader\"\n\tdata-field-id=\"15\"\n\tdata-form-id=\"43\"\n\tdata-input-name=\"wpforms_43_15\"\n\tdata-extensions=\"jpg,jpeg,jpe,gif,png,bmp,tiff,tif,webp,avif,ico,heic,heif,heics,heifs,asf,asx,wmv,wmx,wm,avi,divx,mov,qt,mpeg,mpg,mpe,mp4,m4v,ogv,webm,mkv,3gp,3gpp,3g2,3gp2,txt,asc,c,cc,h,srt,csv,tsv,ics,rtx,css,vtt,mp3,m4a,m4b,aac,ra,ram,wav,ogg,oga,flac,mid,midi,wma,wax,mka,rtf,pdf,class,tar,zip,gz,gzip,rar,7z,psd,xcf,doc,pot,pps,ppt,wri,xla,xls,xlt,xlw,mpp,docx,docm,dotx,dotm,xlsx,xlsm,xlsb,xltx,xltm,xlam,pptx,pptm,ppsx,ppsm,potx,potm,ppam,sldx,sldm,onetoc,onetoc2,onepkg,oxps,xps,odt,odp,ods,odg,odc,odb,odf,wp,wpd,key,numbers,pages\"\n\tdata-max-size=\"268435456\"\n\tdata-max-file-number=\"1\"\n\tdata-post-max-size=\"268435456\"\n    data-max-parallel-uploads=\"4\"\n    data-parallel-uploads=\"true\"\n\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg viewBox=\"0 0 1024 1024\" focusable=\"false\" class=\"\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"#B1B1B1\" aria-hidden=\"true\"><path d=\"M885.2 446.3l-.2-.8-112.2-285.1c-5-16.1-19.9-27.2-36.8-27.2H281.2c-17 0-32.1 11.3-36.9 27.6L139.4 443l-.3.7-.2.8c-1.3 4.9-1.7 9.9-1 14.8-.1 1.6-.2 3.2-.2 4.8V830a60.9 60.9 0 0 0 60.8 60.8h627.2c33.5 0 60.8-27.3 60.9-60.8V464.1c0-1.3 0-2.6-.1-3.7.4-4.9 0-9.6-1.3-14.1zm-295.8-43l-.3 15.7c-.8 44.9-31.8 75.1-77.1 75.1-22.1 0-41.1-7.1-54.8-20.6S436 441.2 435.6 419l-.3-15.7H229.5L309 210h399.2l81.7 193.3H589.4zm-375 76.8h157.3c24.3 57.1 76 90.8 140.4 90.8 33.7 0 65-9.4 90.3-27.2 22.2-15.6 39.5-37.4 50.7-63.6h156.5V814H214.4V480.1z\"><\/path><\/svg>\n\t\t<span class=\"modern-title\">\n\t\t\tHaz clic o arrastra un archivo a este \u00e1rea para subirlo.\t\t<\/span>\n\n\t\t\t<\/div>\n<\/div>\n<input type=\"text\" class=\"dropzone-input\"\n\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\tid=\"wpforms-43-field_15\"\n\tname=\"wpforms_43_15\" >\n<div class=\"wpforms-field-description\">Estas informaciones son \u00fatiles para entender el caso. No es obligatorio que la envies.<\/div><\/div><div id=\"wpforms-43-field_18-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-id=\"18\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_18\">Adjuntar captura de la notificaci\u00f3n de la plataforma<\/label><div class=\"wpforms-uploader\"\n\tdata-field-id=\"18\"\n\tdata-form-id=\"43\"\n\tdata-input-name=\"wpforms_43_18\"\n\tdata-extensions=\"jpg,jpeg,jpe,gif,png,bmp,tiff,tif,webp,avif,ico,heic,heif,heics,heifs,asf,asx,wmv,wmx,wm,avi,divx,mov,qt,mpeg,mpg,mpe,mp4,m4v,ogv,webm,mkv,3gp,3gpp,3g2,3gp2,txt,asc,c,cc,h,srt,csv,tsv,ics,rtx,css,vtt,mp3,m4a,m4b,aac,ra,ram,wav,ogg,oga,flac,mid,midi,wma,wax,mka,rtf,pdf,class,tar,zip,gz,gzip,rar,7z,psd,xcf,doc,pot,pps,ppt,wri,xla,xls,xlt,xlw,mpp,docx,docm,dotx,dotm,xlsx,xlsm,xlsb,xltx,xltm,xlam,pptx,pptm,ppsx,ppsm,potx,potm,ppam,sldx,sldm,onetoc,onetoc2,onepkg,oxps,xps,odt,odp,ods,odg,odc,odb,odf,wp,wpd,key,numbers,pages\"\n\tdata-max-size=\"268435456\"\n\tdata-max-file-number=\"1\"\n\tdata-post-max-size=\"268435456\"\n    data-max-parallel-uploads=\"4\"\n    data-parallel-uploads=\"true\"\n\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg viewBox=\"0 0 1024 1024\" focusable=\"false\" class=\"\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"#B1B1B1\" aria-hidden=\"true\"><path d=\"M885.2 446.3l-.2-.8-112.2-285.1c-5-16.1-19.9-27.2-36.8-27.2H281.2c-17 0-32.1 11.3-36.9 27.6L139.4 443l-.3.7-.2.8c-1.3 4.9-1.7 9.9-1 14.8-.1 1.6-.2 3.2-.2 4.8V830a60.9 60.9 0 0 0 60.8 60.8h627.2c33.5 0 60.8-27.3 60.9-60.8V464.1c0-1.3 0-2.6-.1-3.7.4-4.9 0-9.6-1.3-14.1zm-295.8-43l-.3 15.7c-.8 44.9-31.8 75.1-77.1 75.1-22.1 0-41.1-7.1-54.8-20.6S436 441.2 435.6 419l-.3-15.7H229.5L309 210h399.2l81.7 193.3H589.4zm-375 76.8h157.3c24.3 57.1 76 90.8 140.4 90.8 33.7 0 65-9.4 90.3-27.2 22.2-15.6 39.5-37.4 50.7-63.6h156.5V814H214.4V480.1z\"><\/path><\/svg>\n\t\t<span class=\"modern-title\">\n\t\t\tHaz clic o arrastra un archivo a este \u00e1rea para subirlo.\t\t<\/span>\n\n\t\t\t<\/div>\n<\/div>\n<input type=\"text\" class=\"dropzone-input\"\n\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\tid=\"wpforms-43-field_18\"\n\tname=\"wpforms_43_18\" >\n<div class=\"wpforms-field-description\">Estas informaciones son \u00fatiles para entender el caso. No es obligatorio que la envies.<\/div><\/div><div id=\"wpforms-43-field_16-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"16\"><label class=\"wpforms-field-label\" for=\"wpforms-43-field_16\">Tu mail <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-43-field_16\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][16]\" required><\/div><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"43\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" class=\"wpforms-submit \" id=\"wpforms-submit-43\" value=\"wpforms-submit\" aria-live=\"assertive\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\">Enviar<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/observacom.org\/compartetucaso\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37d9a1e elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37d9a1e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-795697f\" data-id=\"795697f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4575bc1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4575bc1\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-02b996a elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"02b996a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-82becd4\" data-id=\"82becd4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d34160a elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d34160a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"MsoNormal\" style=\"margin-bottom: 6.0pt;\"><b>RESERVA DE TU INFORMACI\u00d3N PERSONAL<br \/><\/b>En nuestro formulario no te solicitamos como dato obligatorio tu nombre y nos comprometemos a conservar confidencialidad de esta informaci\u00f3n que compartes, que s\u00f3lo haremos p\u00fablica con tu aprobaci\u00f3n previa y expresa.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-04e9288 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"04e9288\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33776b4\" data-id=\"33776b4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9b2d59 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f9b2d59\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Las remociones de contenidos que usan las grandes plataformas por supuestamente incumplir sus t\u00e9rminos de servicio o normas comunitarias es una grave y unilateral medida que puede afectar el derecho a la libertad de expresi\u00f3n de quien publica, pero tambi\u00e9n del que busca y tiene derecho a recibir esa publicaci\u00f3n. La suspensi\u00f3n o bloqueo de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-14","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/observacom.org\/compartetucaso\/index.php\/wp-json\/wp\/v2\/pages\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/observacom.org\/compartetucaso\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/observacom.org\/compartetucaso\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/observacom.org\/compartetucaso\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/observacom.org\/compartetucaso\/index.php\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":254,"href":"https:\/\/observacom.org\/compartetucaso\/index.php\/wp-json\/wp\/v2\/pages\/14\/revisions"}],"predecessor-version":[{"id":309,"href":"https:\/\/observacom.org\/compartetucaso\/index.php\/wp-json\/wp\/v2\/pages\/14\/revisions\/309"}],"wp:attachment":[{"href":"https:\/\/observacom.org\/compartetucaso\/index.php\/wp-json\/wp\/v2\/media?parent=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}